{"id":22563,"date":"2025-11-26T16:42:04","date_gmt":"2025-11-26T15:42:04","guid":{"rendered":"https:\/\/placng.org\/i\/?post_type=documents&#038;p=22563"},"modified":"2025-11-27T16:44:59","modified_gmt":"2025-11-27T15:44:59","slug":"senate-order-paper-wednesday-26th-november-2025","status":"publish","type":"documents","link":"https:\/\/placng.org\/i\/documents\/senate-order-paper-wednesday-26th-november-2025\/","title":{"rendered":"Senate order paper, Wednesday, 26th November, 2025"},"author":2,"featured_media":0,"template":"","document_type":[8,17],"class_list":["post-22563","documents","type-documents","status-publish","hentry","document_type-legist_papers","document_type-senate_op"],"acf":[],"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/placng.org\/i\/author\/olumide-adebayo\/","display_name":"PLAC"},"relative_dates":{"created":"Posted 8 months ago","modified":"Updated 8 months ago"},"absolute_dates":{"created":"Posted on November 26, 2025","modified":"Updated on November 27, 2025"},"absolute_dates_time":{"created":"Posted on November 26, 2025 4:42 pm","modified":"Updated on November 27, 2025 4:44 pm"},"featured_img_caption":"","tax_additional":{"document_type":{"linked":["<a href=\"https:\/\/placng.org\/i\/document_type\/legist_papers\/\" class=\"advgb-post-tax-term\">Legislative Papers<\/a>","<a href=\"https:\/\/placng.org\/i\/document_type\/senate_op\/\" class=\"advgb-post-tax-term\">Senate Order Papers<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Legislative Papers<\/span>","<span class=\"advgb-post-tax-term\">Senate Order Papers<\/span>"],"slug":"document_type","name":"Document Type"}},"series_order":"","_links":{"self":[{"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/documents\/22563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/documents"}],"about":[{"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/types\/documents"}],"version-history":[{"count":1,"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/documents\/22563\/revisions"}],"predecessor-version":[{"id":22570,"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/documents\/22563\/revisions\/22570"}],"wp:attachment":[{"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/media?parent=22563"}],"wp:term":[{"taxonomy":"document_type","embeddable":true,"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/document_type?post=22563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}