{"id":22536,"date":"2025-11-18T07:45:36","date_gmt":"2025-11-18T06:45:36","guid":{"rendered":"https:\/\/placng.org\/i\/?post_type=documents&#038;p=22536"},"modified":"2025-11-19T07:48:36","modified_gmt":"2025-11-19T06:48:36","slug":"senate-order-paper-tuesday-18th-november-2025","status":"publish","type":"documents","link":"https:\/\/placng.org\/i\/documents\/senate-order-paper-tuesday-18th-november-2025\/","title":{"rendered":"Senate order paper, Tuesday, 18th November, 2025"},"author":2,"featured_media":0,"template":"","document_type":[8,17],"class_list":["post-22536","documents","type-documents","status-publish","hentry","document_type-legist_papers","document_type-senate_op"],"acf":[],"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/placng.org\/i\/author\/olumide-adebayo\/","display_name":"PLAC"},"relative_dates":{"created":"Posted 8 months ago","modified":"Updated 8 months ago"},"absolute_dates":{"created":"Posted on November 18, 2025","modified":"Updated on November 19, 2025"},"absolute_dates_time":{"created":"Posted on November 18, 2025 7:45 am","modified":"Updated on November 19, 2025 7:48 am"},"featured_img_caption":"","tax_additional":{"document_type":{"linked":["<a href=\"https:\/\/placng.org\/i\/document_type\/legist_papers\/\" class=\"advgb-post-tax-term\">Legislative Papers<\/a>","<a href=\"https:\/\/placng.org\/i\/document_type\/senate_op\/\" class=\"advgb-post-tax-term\">Senate Order Papers<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Legislative Papers<\/span>","<span class=\"advgb-post-tax-term\">Senate Order Papers<\/span>"],"slug":"document_type","name":"Document Type"}},"series_order":"","_links":{"self":[{"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/documents\/22536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/documents"}],"about":[{"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/types\/documents"}],"version-history":[{"count":1,"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/documents\/22536\/revisions"}],"predecessor-version":[{"id":22546,"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/documents\/22536\/revisions\/22546"}],"wp:attachment":[{"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/media?parent=22536"}],"wp:term":[{"taxonomy":"document_type","embeddable":true,"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/document_type?post=22536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}