{"id":21897,"date":"2025-06-24T17:40:12","date_gmt":"2025-06-24T16:40:12","guid":{"rendered":"https:\/\/placng.org\/i\/?post_type=documents&#038;p=21897"},"modified":"2025-06-24T17:40:12","modified_gmt":"2025-06-24T16:40:12","slug":"senate-order-paper-tuesday-24th-june-2025","status":"publish","type":"documents","link":"https:\/\/placng.org\/i\/documents\/senate-order-paper-tuesday-24th-june-2025\/","title":{"rendered":"Senate order paper, Tuesday, 24th June, 2025"},"author":2,"featured_media":0,"template":"","document_type":[8,17],"class_list":["post-21897","documents","type-documents","status-publish","hentry","document_type-legist_papers","document_type-senate_op"],"acf":[],"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/placng.org\/i\/author\/olumide-adebayo\/","display_name":"PLAC"},"relative_dates":{"created":"Posted 1 year ago","modified":"Updated 1 year ago"},"absolute_dates":{"created":"Posted on June 24, 2025","modified":"Updated on June 24, 2025"},"absolute_dates_time":{"created":"Posted on June 24, 2025 5:40 pm","modified":"Updated on June 24, 2025 5:40 pm"},"featured_img_caption":"","tax_additional":{"document_type":{"linked":["<a href=\"https:\/\/placng.org\/i\/document_type\/legist_papers\/\" class=\"advgb-post-tax-term\">Legislative Papers<\/a>","<a href=\"https:\/\/placng.org\/i\/document_type\/senate_op\/\" class=\"advgb-post-tax-term\">Senate Order Papers<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Legislative Papers<\/span>","<span class=\"advgb-post-tax-term\">Senate Order Papers<\/span>"],"slug":"document_type","name":"Document Type"}},"series_order":"","_links":{"self":[{"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/documents\/21897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/documents"}],"about":[{"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/types\/documents"}],"version-history":[{"count":1,"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/documents\/21897\/revisions"}],"predecessor-version":[{"id":21901,"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/documents\/21897\/revisions\/21901"}],"wp:attachment":[{"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/media?parent=21897"}],"wp:term":[{"taxonomy":"document_type","embeddable":true,"href":"https:\/\/placng.org\/i\/wp-json\/wp\/v2\/document_type?post=21897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}